{"id":297316,"date":"2022-04-22T15:23:55","date_gmt":"2022-04-22T15:23:55","guid":{"rendered":"https:\/\/jamesmckiernanlawyers.com\/ubicaciones\/santa-barbara-ca\/"},"modified":"2022-12-20T06:17:17","modified_gmt":"2022-12-20T06:17:17","slug":"santa-barbara-ca","status":"publish","type":"page","link":"https:\/\/jamesmckiernanlawyers.com\/es\/ubicaciones\/santa-barbara-ca\/","title":{"rendered":"Santa Barbara, CA"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"[...]","protected":false},"author":2,"featured_media":138395,"parent":296830,"menu_order":3,"comment_status":"closed","ping_status":"closed","template":"practice-areas.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-297316","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Los mejores abogados de lesiones por accidentes en Santa B\u00e1rbara, CA | James McKiernan Lawyers<\/title>\n<meta name=\"description\" content=\"Si result\u00f3 lesionado por causas ajenas a usted, comun\u00edquese hoy con los abogados de lesiones por accidentes de Santa B\u00e1rbara en James McKiernan Lawyers para una consulta gratuita.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Los mejores abogados de lesiones por accidentes en Santa B\u00e1rbara, CA | James McKiernan Lawyers\" \/>\n<meta property=\"og:description\" content=\"Si result\u00f3 lesionado por causas ajenas a usted, comun\u00edquese hoy con los abogados de lesiones por accidentes de Santa B\u00e1rbara en James McKiernan Lawyers para una consulta gratuita.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jamesmckiernanlawyers.com\/es\/ubicaciones\/santa-barbara-ca\/\" \/>\n<meta property=\"og:site_name\" content=\"James McKiernan Lawyers\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/James-McKiernan-Lawyers-305870092829848\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-20T06:17:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jamesmckiernanlawyers.com\/wp-content\/uploads\/2017\/07\/Medical_Negligence_Chart.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Los mejores abogados de lesiones por accidentes en Santa B\u00e1rbara, CA | James McKiernan Lawyers\" \/>\n<meta name=\"twitter:description\" content=\"Si result\u00f3 lesionado por causas ajenas a usted, comun\u00edquese hoy con los abogados de lesiones por accidentes de Santa B\u00e1rbara en James McKiernan Lawyers para una consulta gratuita.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/jamesmckiernanlawyers.com\/wp-content\/uploads\/2017\/07\/Medical_Negligence_Chart.jpg\" \/>\n<meta name=\"twitter:site\" content=\"@McKiernanLaw\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jamesmckiernanlawyers.com\\\/es\\\/ubicaciones\\\/santa-barbara-ca\\\/\",\"url\":\"https:\\\/\\\/jamesmckiernanlawyers.com\\\/es\\\/ubicaciones\\\/santa-barbara-ca\\\/\",\"name\":\"Los mejores abogados de lesiones por accidentes en Santa B\u00e1rbara, CA | James McKiernan Lawyers\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jamesmckiernanlawyers.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jamesmckiernanlawyers.com\\\/es\\\/ubicaciones\\\/santa-barbara-ca\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jamesmckiernanlawyers.com\\\/es\\\/ubicaciones\\\/santa-barbara-ca\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jamesmckiernanlawyers.com\\\/wp-content\\\/uploads\\\/2017\\\/07\\\/Medical_Negligence_Chart.jpg\",\"datePublished\":\"2022-04-22T15:23:55+00:00\",\"dateModified\":\"2022-12-20T06:17:17+00:00\",\"description\":\"Si result\u00f3 lesionado por causas ajenas a usted, comun\u00edquese hoy con los abogados de lesiones por accidentes de Santa B\u00e1rbara en James McKiernan Lawyers para una consulta gratuita.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jamesmckiernanlawyers.com\\\/es\\\/ubicaciones\\\/santa-barbara-ca\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jamesmckiernanlawyers.com\\\/es\\\/ubicaciones\\\/santa-barbara-ca\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/jamesmckiernanlawyers.com\\\/es\\\/ubicaciones\\\/santa-barbara-ca\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jamesmckiernanlawyers.com\\\/wp-content\\\/uploads\\\/2017\\\/07\\\/Medical_Negligence_Chart.jpg\",\"contentUrl\":\"https:\\\/\\\/jamesmckiernanlawyers.com\\\/wp-content\\\/uploads\\\/2017\\\/07\\\/Medical_Negligence_Chart.jpg\",\"width\":200,\"height\":150,\"caption\":\"Picture of medical negligence chart\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jamesmckiernanlawyers.com\\\/es\\\/ubicaciones\\\/santa-barbara-ca\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/jamesmckiernanlawyers.com\\\/es\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ubicaciones\",\"item\":\"https:\\\/\\\/jamesmckiernanlawyers.com\\\/es\\\/ubicaciones\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Santa Barbara, CA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jamesmckiernanlawyers.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/jamesmckiernanlawyers.com\\\/es\\\/\",\"name\":\"James McKiernan Lawyers\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/jamesmckiernanlawyers.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jamesmckiernanlawyers.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/jamesmckiernanlawyers.com\\\/es\\\/#organization\",\"name\":\"James McKiernan Lawyers\",\"url\":\"https:\\\/\\\/jamesmckiernanlawyers.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/jamesmckiernanlawyers.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/jamesmckiernanlawyers.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/mobile-logo.png\",\"contentUrl\":\"https:\\\/\\\/jamesmckiernanlawyers.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/mobile-logo.png\",\"width\":1188,\"height\":193,\"caption\":\"James McKiernan Lawyers\"},\"image\":{\"@id\":\"https:\\\/\\\/jamesmckiernanlawyers.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/James-McKiernan-Lawyers-305870092829848\",\"https:\\\/\\\/x.com\\\/McKiernanLaw\",\"https:\\\/\\\/www.instagram.com\\\/jamesmckiernanlawyers\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/james-mckiernan-aaa1b318\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Los mejores abogados de lesiones por accidentes en Santa B\u00e1rbara, CA | James McKiernan Lawyers","description":"Si result\u00f3 lesionado por causas ajenas a usted, comun\u00edquese hoy con los abogados de lesiones por accidentes de Santa B\u00e1rbara en James McKiernan Lawyers para una consulta gratuita.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"\/","og_locale":"es_ES","og_type":"article","og_title":"Los mejores abogados de lesiones por accidentes en Santa B\u00e1rbara, CA | James McKiernan Lawyers","og_description":"Si result\u00f3 lesionado por causas ajenas a usted, comun\u00edquese hoy con los abogados de lesiones por accidentes de Santa B\u00e1rbara en James McKiernan Lawyers para una consulta gratuita.","og_url":"https:\/\/jamesmckiernanlawyers.com\/es\/ubicaciones\/santa-barbara-ca\/","og_site_name":"James McKiernan Lawyers","article_publisher":"https:\/\/www.facebook.com\/James-McKiernan-Lawyers-305870092829848","article_modified_time":"2022-12-20T06:17:17+00:00","og_image":[{"url":"https:\/\/jamesmckiernanlawyers.com\/wp-content\/uploads\/2017\/07\/Medical_Negligence_Chart.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_title":"Los mejores abogados de lesiones por accidentes en Santa B\u00e1rbara, CA | James McKiernan Lawyers","twitter_description":"Si result\u00f3 lesionado por causas ajenas a usted, comun\u00edquese hoy con los abogados de lesiones por accidentes de Santa B\u00e1rbara en James McKiernan Lawyers para una consulta gratuita.","twitter_image":"https:\/\/jamesmckiernanlawyers.com\/wp-content\/uploads\/2017\/07\/Medical_Negligence_Chart.jpg","twitter_site":"@McKiernanLaw","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/jamesmckiernanlawyers.com\/es\/ubicaciones\/santa-barbara-ca\/","url":"https:\/\/jamesmckiernanlawyers.com\/es\/ubicaciones\/santa-barbara-ca\/","name":"Los mejores abogados de lesiones por accidentes en Santa B\u00e1rbara, CA | James McKiernan Lawyers","isPartOf":{"@id":"https:\/\/jamesmckiernanlawyers.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jamesmckiernanlawyers.com\/es\/ubicaciones\/santa-barbara-ca\/#primaryimage"},"image":{"@id":"https:\/\/jamesmckiernanlawyers.com\/es\/ubicaciones\/santa-barbara-ca\/#primaryimage"},"thumbnailUrl":"https:\/\/jamesmckiernanlawyers.com\/wp-content\/uploads\/2017\/07\/Medical_Negligence_Chart.jpg","datePublished":"2022-04-22T15:23:55+00:00","dateModified":"2022-12-20T06:17:17+00:00","description":"Si result\u00f3 lesionado por causas ajenas a usted, comun\u00edquese hoy con los abogados de lesiones por accidentes de Santa B\u00e1rbara en James McKiernan Lawyers para una consulta gratuita.","breadcrumb":{"@id":"https:\/\/jamesmckiernanlawyers.com\/es\/ubicaciones\/santa-barbara-ca\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jamesmckiernanlawyers.com\/es\/ubicaciones\/santa-barbara-ca\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/jamesmckiernanlawyers.com\/es\/ubicaciones\/santa-barbara-ca\/#primaryimage","url":"https:\/\/jamesmckiernanlawyers.com\/wp-content\/uploads\/2017\/07\/Medical_Negligence_Chart.jpg","contentUrl":"https:\/\/jamesmckiernanlawyers.com\/wp-content\/uploads\/2017\/07\/Medical_Negligence_Chart.jpg","width":200,"height":150,"caption":"Picture of medical negligence chart"},{"@type":"BreadcrumbList","@id":"https:\/\/jamesmckiernanlawyers.com\/es\/ubicaciones\/santa-barbara-ca\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/jamesmckiernanlawyers.com\/es\/home\/"},{"@type":"ListItem","position":2,"name":"Ubicaciones","item":"https:\/\/jamesmckiernanlawyers.com\/es\/ubicaciones\/"},{"@type":"ListItem","position":3,"name":"Santa Barbara, CA"}]},{"@type":"WebSite","@id":"https:\/\/jamesmckiernanlawyers.com\/es\/#website","url":"https:\/\/jamesmckiernanlawyers.com\/es\/","name":"James McKiernan Lawyers","description":"","publisher":{"@id":"https:\/\/jamesmckiernanlawyers.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jamesmckiernanlawyers.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/jamesmckiernanlawyers.com\/es\/#organization","name":"James McKiernan Lawyers","url":"https:\/\/jamesmckiernanlawyers.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/jamesmckiernanlawyers.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/jamesmckiernanlawyers.com\/wp-content\/uploads\/2021\/02\/mobile-logo.png","contentUrl":"https:\/\/jamesmckiernanlawyers.com\/wp-content\/uploads\/2021\/02\/mobile-logo.png","width":1188,"height":193,"caption":"James McKiernan Lawyers"},"image":{"@id":"https:\/\/jamesmckiernanlawyers.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/James-McKiernan-Lawyers-305870092829848","https:\/\/x.com\/McKiernanLaw","https:\/\/www.instagram.com\/jamesmckiernanlawyers\/","https:\/\/www.linkedin.com\/in\/james-mckiernan-aaa1b318"]}]}},"_links":{"self":[{"href":"https:\/\/jamesmckiernanlawyers.com\/es\/wp-json\/wp\/v2\/pages\/297316","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jamesmckiernanlawyers.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/jamesmckiernanlawyers.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/jamesmckiernanlawyers.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/jamesmckiernanlawyers.com\/es\/wp-json\/wp\/v2\/comments?post=297316"}],"version-history":[{"count":0,"href":"https:\/\/jamesmckiernanlawyers.com\/es\/wp-json\/wp\/v2\/pages\/297316\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/jamesmckiernanlawyers.com\/es\/wp-json\/wp\/v2\/pages\/296830"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jamesmckiernanlawyers.com\/es\/wp-json\/wp\/v2\/media\/138395"}],"wp:attachment":[{"href":"https:\/\/jamesmckiernanlawyers.com\/es\/wp-json\/wp\/v2\/media?parent=297316"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}