{"id":296916,"date":"2021-11-05T14:55:38","date_gmt":"2021-11-05T14:55:38","guid":{"rendered":"https:\/\/jamesmckiernanlawyers.com\/politica-de-privacidad\/"},"modified":"2021-11-05T14:55:38","modified_gmt":"2021-11-05T14:55:38","slug":"politica-de-privacidad","status":"publish","type":"page","link":"https:\/\/jamesmckiernanlawyers.com\/es\/politica-de-privacidad\/","title":{"rendered":"Pol\u00edtica de privacidad"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"[...]","protected":false},"author":5,"featured_media":110,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"practice-areas.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-296916","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pol\u00edtica de privacidad | James McKiernan Lawyers<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pol\u00edtica de privacidad | James McKiernan Lawyers\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jamesmckiernanlawyers.com\/es\/politica-de-privacidad\/\" \/>\n<meta property=\"og:site_name\" content=\"James McKiernan Lawyers\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/James-McKiernan-Lawyers-305870092829848\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jamesmckiernanlawyers.com\/wp-content\/uploads\/2020\/11\/mckiernan-img-circle-img.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Pol\u00edtica de privacidad | James McKiernan Lawyers\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/jamesmckiernanlawyers.com\/wp-content\/uploads\/2020\/11\/mckiernan-img-circle-img.png\" \/>\n<meta name=\"twitter:site\" content=\"@McKiernanLaw\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jamesmckiernanlawyers.com\\\/es\\\/politica-de-privacidad\\\/\",\"url\":\"https:\\\/\\\/jamesmckiernanlawyers.com\\\/es\\\/politica-de-privacidad\\\/\",\"name\":\"Pol\u00edtica de privacidad | James McKiernan Lawyers\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jamesmckiernanlawyers.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jamesmckiernanlawyers.com\\\/es\\\/politica-de-privacidad\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jamesmckiernanlawyers.com\\\/es\\\/politica-de-privacidad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jamesmckiernanlawyers.com\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/mckiernan-img-circle-img.png\",\"datePublished\":\"2021-11-05T14:55:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jamesmckiernanlawyers.com\\\/es\\\/politica-de-privacidad\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jamesmckiernanlawyers.com\\\/es\\\/politica-de-privacidad\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/jamesmckiernanlawyers.com\\\/es\\\/politica-de-privacidad\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jamesmckiernanlawyers.com\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/mckiernan-img-circle-img.png\",\"contentUrl\":\"https:\\\/\\\/jamesmckiernanlawyers.com\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/mckiernan-img-circle-img.png\",\"width\":490,\"height\":494,\"caption\":\"Man in suit with American flag background.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jamesmckiernanlawyers.com\\\/es\\\/politica-de-privacidad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/jamesmckiernanlawyers.com\\\/es\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pol\u00edtica de privacidad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jamesmckiernanlawyers.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/jamesmckiernanlawyers.com\\\/es\\\/\",\"name\":\"James McKiernan Lawyers\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/jamesmckiernanlawyers.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jamesmckiernanlawyers.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/jamesmckiernanlawyers.com\\\/es\\\/#organization\",\"name\":\"James McKiernan Lawyers\",\"url\":\"https:\\\/\\\/jamesmckiernanlawyers.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/jamesmckiernanlawyers.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/jamesmckiernanlawyers.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/mobile-logo.png\",\"contentUrl\":\"https:\\\/\\\/jamesmckiernanlawyers.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/mobile-logo.png\",\"width\":1188,\"height\":193,\"caption\":\"James McKiernan Lawyers\"},\"image\":{\"@id\":\"https:\\\/\\\/jamesmckiernanlawyers.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/James-McKiernan-Lawyers-305870092829848\",\"https:\\\/\\\/x.com\\\/McKiernanLaw\",\"https:\\\/\\\/www.instagram.com\\\/jamesmckiernanlawyers\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/james-mckiernan-aaa1b318\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pol\u00edtica de privacidad | James McKiernan Lawyers","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"\/","og_locale":"es_ES","og_type":"article","og_title":"Pol\u00edtica de privacidad | James McKiernan Lawyers","og_url":"https:\/\/jamesmckiernanlawyers.com\/es\/politica-de-privacidad\/","og_site_name":"James McKiernan Lawyers","article_publisher":"https:\/\/www.facebook.com\/James-McKiernan-Lawyers-305870092829848","og_image":[{"url":"https:\/\/jamesmckiernanlawyers.com\/wp-content\/uploads\/2020\/11\/mckiernan-img-circle-img.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_title":"Pol\u00edtica de privacidad | James McKiernan Lawyers","twitter_image":"https:\/\/jamesmckiernanlawyers.com\/wp-content\/uploads\/2020\/11\/mckiernan-img-circle-img.png","twitter_site":"@McKiernanLaw","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/jamesmckiernanlawyers.com\/es\/politica-de-privacidad\/","url":"https:\/\/jamesmckiernanlawyers.com\/es\/politica-de-privacidad\/","name":"Pol\u00edtica de privacidad | James McKiernan Lawyers","isPartOf":{"@id":"https:\/\/jamesmckiernanlawyers.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jamesmckiernanlawyers.com\/es\/politica-de-privacidad\/#primaryimage"},"image":{"@id":"https:\/\/jamesmckiernanlawyers.com\/es\/politica-de-privacidad\/#primaryimage"},"thumbnailUrl":"https:\/\/jamesmckiernanlawyers.com\/wp-content\/uploads\/2020\/11\/mckiernan-img-circle-img.png","datePublished":"2021-11-05T14:55:38+00:00","breadcrumb":{"@id":"https:\/\/jamesmckiernanlawyers.com\/es\/politica-de-privacidad\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jamesmckiernanlawyers.com\/es\/politica-de-privacidad\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/jamesmckiernanlawyers.com\/es\/politica-de-privacidad\/#primaryimage","url":"https:\/\/jamesmckiernanlawyers.com\/wp-content\/uploads\/2020\/11\/mckiernan-img-circle-img.png","contentUrl":"https:\/\/jamesmckiernanlawyers.com\/wp-content\/uploads\/2020\/11\/mckiernan-img-circle-img.png","width":490,"height":494,"caption":"Man in suit with American flag background."},{"@type":"BreadcrumbList","@id":"https:\/\/jamesmckiernanlawyers.com\/es\/politica-de-privacidad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/jamesmckiernanlawyers.com\/es\/home\/"},{"@type":"ListItem","position":2,"name":"Pol\u00edtica de privacidad"}]},{"@type":"WebSite","@id":"https:\/\/jamesmckiernanlawyers.com\/es\/#website","url":"https:\/\/jamesmckiernanlawyers.com\/es\/","name":"James McKiernan Lawyers","description":"","publisher":{"@id":"https:\/\/jamesmckiernanlawyers.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jamesmckiernanlawyers.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/jamesmckiernanlawyers.com\/es\/#organization","name":"James McKiernan Lawyers","url":"https:\/\/jamesmckiernanlawyers.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/jamesmckiernanlawyers.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/jamesmckiernanlawyers.com\/wp-content\/uploads\/2021\/02\/mobile-logo.png","contentUrl":"https:\/\/jamesmckiernanlawyers.com\/wp-content\/uploads\/2021\/02\/mobile-logo.png","width":1188,"height":193,"caption":"James McKiernan Lawyers"},"image":{"@id":"https:\/\/jamesmckiernanlawyers.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/James-McKiernan-Lawyers-305870092829848","https:\/\/x.com\/McKiernanLaw","https:\/\/www.instagram.com\/jamesmckiernanlawyers\/","https:\/\/www.linkedin.com\/in\/james-mckiernan-aaa1b318"]}]}},"_links":{"self":[{"href":"https:\/\/jamesmckiernanlawyers.com\/es\/wp-json\/wp\/v2\/pages\/296916","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jamesmckiernanlawyers.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/jamesmckiernanlawyers.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/jamesmckiernanlawyers.com\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/jamesmckiernanlawyers.com\/es\/wp-json\/wp\/v2\/comments?post=296916"}],"version-history":[{"count":0,"href":"https:\/\/jamesmckiernanlawyers.com\/es\/wp-json\/wp\/v2\/pages\/296916\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jamesmckiernanlawyers.com\/es\/wp-json\/wp\/v2\/media\/110"}],"wp:attachment":[{"href":"https:\/\/jamesmckiernanlawyers.com\/es\/wp-json\/wp\/v2\/media?parent=296916"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}