{"id":296469,"date":"2021-07-16T19:10:17","date_gmt":"2021-07-16T19:10:17","guid":{"rendered":"https:\/\/jamesmckiernanlawyers.com\/lesion-personal\/casos-de-muerte-por-negligencia\/"},"modified":"2022-04-08T20:46:21","modified_gmt":"2022-04-08T20:46:21","slug":"casos-de-muerte-por-negligencia","status":"publish","type":"page","link":"https:\/\/jamesmckiernanlawyers.com\/es\/lesion-personal\/casos-de-muerte-por-negligencia\/","title":{"rendered":"Casos de Muerte por Negligencia"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"[...]","protected":false},"author":5,"featured_media":296689,"parent":296465,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"practice-areas.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-296469","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfPerdiste a un ser querido? Comun\u00edquese con nuestros abogados de muerte por negligencia | James McKiernan<\/title>\n<meta name=\"description\" content=\"Comun\u00edquese con nuestros abogados de muerte por negligencia de James McKiernan al (800) 200-4878 o en l\u00ednea para una consulta sin riesgos o preguntas sobre su caso.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfPerdiste a un ser querido? Comun\u00edquese con nuestros abogados de muerte por negligencia | James McKiernan\" \/>\n<meta property=\"og:description\" content=\"Comun\u00edquese con nuestros abogados de muerte por negligencia de James McKiernan al (800) 200-4878 o en l\u00ednea para una consulta sin riesgos o preguntas sobre su caso.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jamesmckiernanlawyers.com\/es\/lesion-personal\/casos-de-muerte-por-negligencia\/\" \/>\n<meta property=\"og:site_name\" content=\"James McKiernan Lawyers\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/James-McKiernan-Lawyers-305870092829848\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-08T20:46:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jamesmckiernanlawyers.com\/wp-content\/uploads\/2021\/08\/wrongful-death-banner-img-cq.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"\u00bfPerdiste a un ser querido? Comun\u00edquese con nuestros abogados de muerte por negligencia | James McKiernan\" \/>\n<meta name=\"twitter:description\" content=\"Comun\u00edquese con nuestros abogados de muerte por negligencia de James McKiernan al (800) 200-4878 o en l\u00ednea para una consulta sin riesgos o preguntas sobre su caso.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/jamesmckiernanlawyers.com\/wp-content\/uploads\/2021\/08\/wrongful-death-banner-img-cq.jpg\" \/>\n<meta name=\"twitter:site\" content=\"@McKiernanLaw\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jamesmckiernanlawyers.com\\\/es\\\/lesion-personal\\\/casos-de-muerte-por-negligencia\\\/\",\"url\":\"https:\\\/\\\/jamesmckiernanlawyers.com\\\/es\\\/lesion-personal\\\/casos-de-muerte-por-negligencia\\\/\",\"name\":\"\u00bfPerdiste a un ser querido? Comun\u00edquese con nuestros abogados de muerte por negligencia | James McKiernan\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jamesmckiernanlawyers.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jamesmckiernanlawyers.com\\\/es\\\/lesion-personal\\\/casos-de-muerte-por-negligencia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jamesmckiernanlawyers.com\\\/es\\\/lesion-personal\\\/casos-de-muerte-por-negligencia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jamesmckiernanlawyers.com\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/wrongful-death-banner-img-cq.jpg\",\"datePublished\":\"2021-07-16T19:10:17+00:00\",\"dateModified\":\"2022-04-08T20:46:21+00:00\",\"description\":\"Comun\u00edquese con nuestros abogados de muerte por negligencia de James McKiernan al (800) 200-4878 o en l\u00ednea para una consulta sin riesgos o preguntas sobre su caso.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jamesmckiernanlawyers.com\\\/es\\\/lesion-personal\\\/casos-de-muerte-por-negligencia\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jamesmckiernanlawyers.com\\\/es\\\/lesion-personal\\\/casos-de-muerte-por-negligencia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/jamesmckiernanlawyers.com\\\/es\\\/lesion-personal\\\/casos-de-muerte-por-negligencia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jamesmckiernanlawyers.com\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/wrongful-death-banner-img-cq.jpg\",\"contentUrl\":\"https:\\\/\\\/jamesmckiernanlawyers.com\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/wrongful-death-banner-img-cq.jpg\",\"width\":1920,\"height\":396,\"caption\":\"Gravestones in a sunlit cemetery.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jamesmckiernanlawyers.com\\\/es\\\/lesion-personal\\\/casos-de-muerte-por-negligencia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/jamesmckiernanlawyers.com\\\/es\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lesi\u00f3n Personal\",\"item\":\"https:\\\/\\\/jamesmckiernanlawyers.com\\\/es\\\/lesion-personal\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Casos de Muerte por Negligencia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jamesmckiernanlawyers.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/jamesmckiernanlawyers.com\\\/es\\\/\",\"name\":\"James McKiernan Lawyers\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/jamesmckiernanlawyers.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jamesmckiernanlawyers.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/jamesmckiernanlawyers.com\\\/es\\\/#organization\",\"name\":\"James McKiernan Lawyers\",\"url\":\"https:\\\/\\\/jamesmckiernanlawyers.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/jamesmckiernanlawyers.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/jamesmckiernanlawyers.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/mobile-logo.png\",\"contentUrl\":\"https:\\\/\\\/jamesmckiernanlawyers.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/mobile-logo.png\",\"width\":1188,\"height\":193,\"caption\":\"James McKiernan Lawyers\"},\"image\":{\"@id\":\"https:\\\/\\\/jamesmckiernanlawyers.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/James-McKiernan-Lawyers-305870092829848\",\"https:\\\/\\\/x.com\\\/McKiernanLaw\",\"https:\\\/\\\/www.instagram.com\\\/jamesmckiernanlawyers\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/james-mckiernan-aaa1b318\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfPerdiste a un ser querido? Comun\u00edquese con nuestros abogados de muerte por negligencia | James McKiernan","description":"Comun\u00edquese con nuestros abogados de muerte por negligencia de James McKiernan al (800) 200-4878 o en l\u00ednea para una consulta sin riesgos o preguntas sobre su caso.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfPerdiste a un ser querido? Comun\u00edquese con nuestros abogados de muerte por negligencia | James McKiernan","og_description":"Comun\u00edquese con nuestros abogados de muerte por negligencia de James McKiernan al (800) 200-4878 o en l\u00ednea para una consulta sin riesgos o preguntas sobre su caso.","og_url":"https:\/\/jamesmckiernanlawyers.com\/es\/lesion-personal\/casos-de-muerte-por-negligencia\/","og_site_name":"James McKiernan Lawyers","article_publisher":"https:\/\/www.facebook.com\/James-McKiernan-Lawyers-305870092829848","article_modified_time":"2022-04-08T20:46:21+00:00","og_image":[{"url":"https:\/\/jamesmckiernanlawyers.com\/wp-content\/uploads\/2021\/08\/wrongful-death-banner-img-cq.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_title":"\u00bfPerdiste a un ser querido? Comun\u00edquese con nuestros abogados de muerte por negligencia | James McKiernan","twitter_description":"Comun\u00edquese con nuestros abogados de muerte por negligencia de James McKiernan al (800) 200-4878 o en l\u00ednea para una consulta sin riesgos o preguntas sobre su caso.","twitter_image":"https:\/\/jamesmckiernanlawyers.com\/wp-content\/uploads\/2021\/08\/wrongful-death-banner-img-cq.jpg","twitter_site":"@McKiernanLaw","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/jamesmckiernanlawyers.com\/es\/lesion-personal\/casos-de-muerte-por-negligencia\/","url":"https:\/\/jamesmckiernanlawyers.com\/es\/lesion-personal\/casos-de-muerte-por-negligencia\/","name":"\u00bfPerdiste a un ser querido? Comun\u00edquese con nuestros abogados de muerte por negligencia | James McKiernan","isPartOf":{"@id":"https:\/\/jamesmckiernanlawyers.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jamesmckiernanlawyers.com\/es\/lesion-personal\/casos-de-muerte-por-negligencia\/#primaryimage"},"image":{"@id":"https:\/\/jamesmckiernanlawyers.com\/es\/lesion-personal\/casos-de-muerte-por-negligencia\/#primaryimage"},"thumbnailUrl":"https:\/\/jamesmckiernanlawyers.com\/wp-content\/uploads\/2021\/08\/wrongful-death-banner-img-cq.jpg","datePublished":"2021-07-16T19:10:17+00:00","dateModified":"2022-04-08T20:46:21+00:00","description":"Comun\u00edquese con nuestros abogados de muerte por negligencia de James McKiernan al (800) 200-4878 o en l\u00ednea para una consulta sin riesgos o preguntas sobre su caso.","breadcrumb":{"@id":"https:\/\/jamesmckiernanlawyers.com\/es\/lesion-personal\/casos-de-muerte-por-negligencia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jamesmckiernanlawyers.com\/es\/lesion-personal\/casos-de-muerte-por-negligencia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/jamesmckiernanlawyers.com\/es\/lesion-personal\/casos-de-muerte-por-negligencia\/#primaryimage","url":"https:\/\/jamesmckiernanlawyers.com\/wp-content\/uploads\/2021\/08\/wrongful-death-banner-img-cq.jpg","contentUrl":"https:\/\/jamesmckiernanlawyers.com\/wp-content\/uploads\/2021\/08\/wrongful-death-banner-img-cq.jpg","width":1920,"height":396,"caption":"Gravestones in a sunlit cemetery."},{"@type":"BreadcrumbList","@id":"https:\/\/jamesmckiernanlawyers.com\/es\/lesion-personal\/casos-de-muerte-por-negligencia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/jamesmckiernanlawyers.com\/es\/home\/"},{"@type":"ListItem","position":2,"name":"Lesi\u00f3n Personal","item":"https:\/\/jamesmckiernanlawyers.com\/es\/lesion-personal\/"},{"@type":"ListItem","position":3,"name":"Casos de Muerte por Negligencia"}]},{"@type":"WebSite","@id":"https:\/\/jamesmckiernanlawyers.com\/es\/#website","url":"https:\/\/jamesmckiernanlawyers.com\/es\/","name":"James McKiernan Lawyers","description":"","publisher":{"@id":"https:\/\/jamesmckiernanlawyers.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jamesmckiernanlawyers.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/jamesmckiernanlawyers.com\/es\/#organization","name":"James McKiernan Lawyers","url":"https:\/\/jamesmckiernanlawyers.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/jamesmckiernanlawyers.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/jamesmckiernanlawyers.com\/wp-content\/uploads\/2021\/02\/mobile-logo.png","contentUrl":"https:\/\/jamesmckiernanlawyers.com\/wp-content\/uploads\/2021\/02\/mobile-logo.png","width":1188,"height":193,"caption":"James McKiernan Lawyers"},"image":{"@id":"https:\/\/jamesmckiernanlawyers.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/James-McKiernan-Lawyers-305870092829848","https:\/\/x.com\/McKiernanLaw","https:\/\/www.instagram.com\/jamesmckiernanlawyers\/","https:\/\/www.linkedin.com\/in\/james-mckiernan-aaa1b318"]}]}},"_links":{"self":[{"href":"https:\/\/jamesmckiernanlawyers.com\/es\/wp-json\/wp\/v2\/pages\/296469","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jamesmckiernanlawyers.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/jamesmckiernanlawyers.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/jamesmckiernanlawyers.com\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/jamesmckiernanlawyers.com\/es\/wp-json\/wp\/v2\/comments?post=296469"}],"version-history":[{"count":0,"href":"https:\/\/jamesmckiernanlawyers.com\/es\/wp-json\/wp\/v2\/pages\/296469\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/jamesmckiernanlawyers.com\/es\/wp-json\/wp\/v2\/pages\/296465"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jamesmckiernanlawyers.com\/es\/wp-json\/wp\/v2\/media\/296689"}],"wp:attachment":[{"href":"https:\/\/jamesmckiernanlawyers.com\/es\/wp-json\/wp\/v2\/media?parent=296469"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}